{"id":771,"date":"2026-09-01T20:37:05","date_gmt":"2026-09-01T18:37:05","guid":{"rendered":"https:\/\/www.asclauzerville.org\/?p=771"},"modified":"2026-09-01T20:37:05","modified_gmt":"2026-09-01T18:37:05","slug":"nouveaute-rentree-2026-2027-ateliers-danglais-pour-les-enfants","status":"publish","type":"post","link":"https:\/\/www.asclauzerville.org\/index.php\/2026\/09\/01\/nouveaute-rentree-2026-2027-ateliers-danglais-pour-les-enfants\/","title":{"rendered":"Nouveaut\u00e9 Rentr\u00e9e 2026\/2027 : Ateliers d&rsquo;Anglais pour les enfants"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En partenariat avec l\u2019association INTERSCOL, l&rsquo;ASCL  propose des ateliers d&rsquo;anglais pour les enfants.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0Tous les lundis, dans la salle des jeunes, <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">de 16h45 \u00e0 17h30 pour les Maternelles-CP <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">de 17h30 \u00e0 18h30 pour les CE1-CE2-CM1-CM2.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une approche sensorielle et ludique de la langue anglaise sera mise en \u0153uvre afin d&rsquo;\u00e9veiller leur int\u00e9r\u00eat \u00e0 la culture anglo-saxonne au travers d&rsquo;activit\u00e9s vari\u00e9es : vocabulaire, jeux (1, 2, 3 soleil, Simons Says, etc&#8230;), jeux de r\u00f4les (marchand, d\u00e9tective, chasse aux tr\u00e9sors, etc&#8230;), chansons, histoires\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En partenariat avec l\u2019association INTERSCOL, l&rsquo;ASCL propose des ateliers d&rsquo;anglais pour les enfants. \u00a0Tous les lundis, dans la salle des &hellip; <\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-771","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.asclauzerville.org\/index.php\/wp-json\/wp\/v2\/posts\/771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asclauzerville.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asclauzerville.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asclauzerville.org\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asclauzerville.org\/index.php\/wp-json\/wp\/v2\/comments?post=771"}],"version-history":[{"count":1,"href":"https:\/\/www.asclauzerville.org\/index.php\/wp-json\/wp\/v2\/posts\/771\/revisions"}],"predecessor-version":[{"id":772,"href":"https:\/\/www.asclauzerville.org\/index.php\/wp-json\/wp\/v2\/posts\/771\/revisions\/772"}],"wp:attachment":[{"href":"https:\/\/www.asclauzerville.org\/index.php\/wp-json\/wp\/v2\/media?parent=771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asclauzerville.org\/index.php\/wp-json\/wp\/v2\/categories?post=771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asclauzerville.org\/index.php\/wp-json\/wp\/v2\/tags?post=771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}